{"id":12847,"date":"2017-08-22T16:00:23","date_gmt":"2017-08-22T19:00:23","guid":{"rendered":"https:\/\/www.autosnuevoschile.cl\/?post_type=product&#038;p=12847"},"modified":"2020-04-16T02:17:09","modified_gmt":"2020-04-16T06:17:09","slug":"bt-50","status":"publish","type":"product","link":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/mazda\/bt-50\/","title":{"rendered":"Mazda BT 50"},"content":{"rendered":"<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='cotizar' class='avia-section main_color avia-section-no-padding avia-no-border-styling avia-bg-style-scroll   container_wrap sidebar_right' style = 'background-color: #0099ff; background-repeat: no-repeat; background-image: url(https:\/\/www.autosnuevoschile.cl\/wp-content\/uploads\/2017\/08\/Mazda-bt-50-Chile-slide.jpg); background-attachment: scroll; background-position: center center; ' data-section-bg-repeat='no-repeat' ><div class='av-section-color-overlay-wrap'><a href='#next-section' title='' class='scroll-down-link' aria-hidden='true' data-av_icon='\ue877' data-av_iconfont='entypo-fontello'><\/a><div class='container' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12847'><div class='entry-content-wrapper clearfix'>\n<div class=\"flex_column av_one_fifth  no_margin flex_column_div first  \" style='padding:20px; border-radius:0px; '><div class='avia-image-container avia_animated_image avia_animate_when_almost_visible top-to-bottom av-styling-    avia-align-center '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><img class='avia_image ' src='https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-content\/uploads\/LOGO-MAZDA.png' alt='Logo autos nuevos Mazda' title='LOGO-MAZDA'   itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><div class=\"flex_column av_one_fifth  no_margin flex_column_div   \" style='padding:20px 20px 20px 80px ; border-radius:0px; '><\/div><div class=\"flex_column av_one_fourth  no_margin flex_column_div   \" style='padding:20px 20px 10px 20px ; background-color:rgba(255,255,255,0.93); border-radius:0px; '><p><div style='padding-bottom:3px;color:#303030;font-size:30px;' class='av-special-heading av-special-heading-h1 custom-color-heading blockquote modern-quote   av-inherit-size '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Mazda BT 50<\/h1><div class ='av-subheading av-subheading_below av_custom_color ' style='font-size:15px;'><p>Mazda BT 50 en Chile, desc\u00fabrelo<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#303030'><\/div><\/div><\/div><br \/>\n<br \/>\n<div style=' margin-top:0px; margin-bottom:0px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:250px; border-color:#0099ff;' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '  style='font-size:19px; '  itemprop=\"text\" ><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"?add-to-cart=12847\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12847\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"12847\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Mazda BT 50&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abMazda BT 50\u00bb se ha a\u00f1adido a tu carrito\">A\u00f1adir al carrito<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12847\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p>\n<\/div><\/section><\/p><\/div><div class=\"flex_column av_one_third  no_margin flex_column_div   \" style='padding:20px 20px 20px 30px ; background-color:rgba(0,11,20,0.8); border-radius:0px; '><p><div style='padding-bottom:5px;color:#ffffff;font-size:24px;' class='av-special-heading av-special-heading-h3 custom-color-heading blockquote modern-quote   av-thin-font av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  ><strong>\u00a1Quiero el Mejor Precio!<\/strong><\/h3><div class ='av-subheading av-subheading_below av_custom_color ' style='font-size:16px;'><p>Solicita aqu\u00ed tu nuevo modelo<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#ffffff'><\/div><\/div><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  av_inherit_color '  style='color:#ffffff; '  itemprop=\"text\" >\n                <div class='gf_browser_gecko gform_wrapper' id='gform_wrapper_11' style='display:none'><form method='post' enctype='multipart\/form-data'  id='gform_11'  action='\/autos-nuevos\/wp-json\/wp\/v2\/product\/12847'>\n                        <div class='gform_body'><ul id='gform_fields_11' class='gform_fields top_label form_sublabel_above description_below'><li id='field_11_8' class='gfield gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_8' >Modelo Mazda:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_8' id='input_11_8'  class='medium gfield_select' tabindex='1'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >\u25bc Selecciona modelo<\/option><option value='Mazda 2 Sedan' >Mazda 2 Sedan<\/option><option value='Mazda 2 Sport' >Mazda 2 Sport<\/option><option value='Mazda 3 Sedan' >Mazda 3 Sedan<\/option><option value='Mazda 5' >Mazda 5<\/option><option value='Mazda 3 Sport' >Mazda 3 Sport<\/option><option value='Mazda 6' >Mazda 6<\/option><option value='Mazda CX-30' >Mazda CX-30<\/option><option value='Mazda CX3' >Mazda CX3<\/option><option value='Mazda CX5' >Mazda CX5<\/option><option value='Mazda CX9' >Mazda CX9<\/option><option value='Mazda MX 5' >Mazda MX 5<\/option><option value='Mazda BT 50' >Mazda BT 50<\/option><\/select><\/div><\/li><li id='field_11_1' class='gfield gf_left_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_1' >Nombre:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_11_1' type='text' value='' class='medium'  tabindex='2'   aria-required=\"true\" aria-invalid=\"false\" \/><\/div><\/li><li id='field_11_9' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_9' >Apellido:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_9' id='input_11_9' type='text' value='' class='medium'  tabindex='3'   aria-required=\"true\" aria-invalid=\"false\" \/><\/div><\/li><li id='field_11_27' class='gfield gf_left_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_27' >Rut:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_27' id='input_11_27' type='text' value='' class='medium'  tabindex='4'   aria-required=\"true\" aria-invalid=\"false\" \/><\/div><\/li><li id='field_11_3' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_3' >Email:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_11_3' type='text' value='' class='medium' tabindex='5'    aria-required=\"true\" aria-invalid=\"false\"\/>\n                        <\/div><\/li><li id='field_11_4' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_4' >Tel\u00e9fono:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_11_4' type='text' value='' class='medium' tabindex='6'   aria-required=\"true\" aria-invalid=\"false\" \/><\/div><\/li><li id='field_11_11' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_11' >Selecciona Regi\u00f3n:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_11' id='input_11_11' onchange='gf_apply_rules(11,[12,13,14,15,16,17,18,19,20,21,22,23,24,25,26]);' class='small gfield_select' tabindex='7'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='RM - Metropolitana de Santiago' >RM - Metropolitana de Santiago<\/option><option value='XV - Arica y Parinacota' >XV - Arica y Parinacota<\/option><option value='I - Tarapac\u00e1' >I - Tarapac\u00e1<\/option><option value='II - Antofagasta' >II - Antofagasta<\/option><option value='III - Atacama' >III - Atacama<\/option><option value='IV - Coquimbo' >IV - Coquimbo<\/option><option value='V - Valpara\u00edso' >V - Valpara\u00edso<\/option><option value='VI - O&#039;Higgins' >VI - O&#039;Higgins<\/option><option value='VII - Maule' >VII - Maule<\/option><option value='VIII - Biob\u00edo' >VIII - Biob\u00edo<\/option><option value='IX - Araucan\u00eda' >IX - Araucan\u00eda<\/option><option value='XIV - Los R\u00edos' >XIV - Los R\u00edos<\/option><option value='X - Los Lagos' >X - Los Lagos<\/option><option value='XI - Ays\u00e9n' >XI - Ays\u00e9n<\/option><option value='XII - Magallanes' >XII - Magallanes<\/option><option value='Sin definir' >Sin definir<\/option><\/select><\/div><\/li><li id='field_11_12' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_12' >Comunas RM:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_12' id='input_11_12'  class='medium gfield_select' tabindex='8'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Alhu\u00e9' >Alhu\u00e9<\/option><option value='Buin' >Buin<\/option><option value='Calera de Tango' >Calera de Tango<\/option><option value='Cerrillos' >Cerrillos<\/option><option value='Cerro Navia' >Cerro Navia<\/option><option value='Colina' >Colina<\/option><option value='Conchal\u00ed' >Conchal\u00ed<\/option><option value='Curacav\u00ed' >Curacav\u00ed<\/option><option value='El Bosque' >El Bosque<\/option><option value='El Monte' >El Monte<\/option><option value='Estaci\u00f3n Central' >Estaci\u00f3n Central<\/option><option value='Huechuraba' >Huechuraba<\/option><option value='Independencia' >Independencia<\/option><option value='Isla de Maipo' >Isla de Maipo<\/option><option value='La Cisterna' >La Cisterna<\/option><option value='La Florida' >La Florida<\/option><option value='La Granja' >La Granja<\/option><option value='La Pintana' >La Pintana<\/option><option value='La Reina' >La Reina<\/option><option value='Lampa' >Lampa<\/option><option value='Las Condes' >Las Condes<\/option><option value='Lo Barnechea' >Lo Barnechea<\/option><option value='Lo Espejo' >Lo Espejo<\/option><option value='Lo Prado' >Lo Prado<\/option><option value='Macul' >Macul<\/option><option value='Maip\u00fa' >Maip\u00fa<\/option><option value='Mar\u00eda Pinto' >Mar\u00eda Pinto<\/option><option value='Melipilla' >Melipilla<\/option><option value='\u00d1u\u00f1oa' >\u00d1u\u00f1oa<\/option><option value='Padre Hurtado' >Padre Hurtado<\/option><option value='Paine' >Paine<\/option><option value='Pedro Aguirre Cerda' >Pedro Aguirre Cerda<\/option><option value='Pe\u00f1aflor' >Pe\u00f1aflor<\/option><option value='Pe\u00f1alolen' >Pe\u00f1alolen<\/option><option value='Pirque' >Pirque<\/option><option value='Providencia' >Providencia<\/option><option value='Pudahuel' >Pudahuel<\/option><option value='Puente Alto' >Puente Alto<\/option><option value='Quilicura' >Quilicura<\/option><option value='Quinta Normal' >Quinta Normal<\/option><option value='Recoleta' >Recoleta<\/option><option value='Renca' >Renca<\/option><option value='San Bernardo' >San Bernardo<\/option><option value='San Joaqu\u00edn' >San Joaqu\u00edn<\/option><option value='San Jos\u00e9 de Maipo' >San Jos\u00e9 de Maipo<\/option><option value='San Miguel' >San Miguel<\/option><option value='San Pedro' >San Pedro<\/option><option value='San Ram\u00f3n' >San Ram\u00f3n<\/option><option value='Santiago' >Santiago<\/option><option value='Talagante' >Talagante<\/option><option value='Tiltil' >Tiltil<\/option><option value='Vitacura' >Vitacura<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_13' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_13' >Comunas Valparaiso:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_13' id='input_11_13'  class='medium gfield_select' tabindex='9'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Algarrobo' >Algarrobo<\/option><option value='Cabildo' >Cabildo<\/option><option value='Calera' >Calera<\/option><option value='Calle larga' >Calle larga<\/option><option value='Cartagena' >Cartagena<\/option><option value='Casablanca' >Casablanca<\/option><option value='Catemu' >Catemu<\/option><option value='Conc\u00f3n' >Conc\u00f3n<\/option><option value='El Quisco' >El Quisco<\/option><option value='El Tabo' >El Tabo<\/option><option value='Hijuelas' >Hijuelas<\/option><option value='Isla de Pascua' >Isla de Pascua<\/option><option value='Juan Fern\u00e1dez' >Juan Fern\u00e1dez<\/option><option value='La Cruz' >La Cruz<\/option><option value='La Ligua' >La Ligua<\/option><option value='Laguna Verde' >Laguna Verde<\/option><option value='Limache' >Limache<\/option><option value='Llaillay' >Llaillay<\/option><option value='Los Andes' >Los Andes<\/option><option value='Nogales' >Nogales<\/option><option value='Olmu\u00e9' >Olmu\u00e9<\/option><option value='Panquehue' >Panquehue<\/option><option value='Papudo' >Papudo<\/option><option value='Petorca' >Petorca<\/option><option value='Puchuncav\u00ed' >Puchuncav\u00ed<\/option><option value='Quillota' >Quillota<\/option><option value='Quilpu\u00e9' >Quilpu\u00e9<\/option><option value='Quintero' >Quintero<\/option><option value='Rinconada' >Rinconada<\/option><option value='San Antonio' >San Antonio<\/option><option value='San Esteban' >San Esteban<\/option><option value='San Felipe' >San Felipe<\/option><option value='Santa Mar\u00eda' >Santa Mar\u00eda<\/option><option value='Santo Domingo' >Santo Domingo<\/option><option value='Valpara\u00edso' >Valpara\u00edso<\/option><option value='Villa Alemana' >Villa Alemana<\/option><option value='Vi\u00f1a de mar' >Vi\u00f1a de mar<\/option><option value='Zapallar' >Zapallar<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_14' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_14' >Comunas Arica y Par.:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_14' id='input_11_14'  class='medium gfield_select' tabindex='10'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Arica' >Arica<\/option><option value='Camarones' >Camarones<\/option><option value='General Lagos' >General Lagos<\/option><option value='Putre' >Putre<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_15' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_15' >Comunas Tarapac\u00e1:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_15' id='input_11_15'  class='medium gfield_select' tabindex='11'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Alto Hospicio' >Alto Hospicio<\/option><option value='Cami\u00f1a' >Cami\u00f1a<\/option><option value='Colchane' >Colchane<\/option><option value='Huara' >Huara<\/option><option value='Iquique' >Iquique<\/option><option value='Pica' >Pica<\/option><option value='Pozo Almonte' >Pozo Almonte<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_16' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_16' >Comunas Antofagasta:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_16' id='input_11_16'  class='medium gfield_select' tabindex='12'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Antofagasta' >Antofagasta<\/option><option value='Calama' >Calama<\/option><option value='Mar\u00eda Elena' >Mar\u00eda Elena<\/option><option value='Mejillones' >Mejillones<\/option><option value='Ollag\u00fce' >Ollag\u00fce<\/option><option value='San Pedro de Atacama' >San Pedro de Atacama<\/option><option value='Sierra Gorda' >Sierra Gorda<\/option><option value='Taltal' >Taltal<\/option><option value='Tocopilla' >Tocopilla<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_17' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_17' >Comunas Atacama:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_17' id='input_11_17'  class='medium gfield_select' tabindex='13'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Alto del Carmen' >Alto del Carmen<\/option><option value='Caldera' >Caldera<\/option><option value='Cha\u00f1aral' >Cha\u00f1aral<\/option><option value='Copiap\u00f3' >Copiap\u00f3<\/option><option value='Diego de Almagro' >Diego de Almagro<\/option><option value='Freirina' >Freirina<\/option><option value='Huasco' >Huasco<\/option><option value='Tierra Amarilla' >Tierra Amarilla<\/option><option value='Vallenar' >Vallenar<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_18' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_18' >Comunas Coquimbo:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_18' id='input_11_18'  class='medium gfield_select' tabindex='14'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Andacollo' >Andacollo<\/option><option value='Canela' >Canela<\/option><option value='Combarbal\u00e1' >Combarbal\u00e1<\/option><option value='Coquimbo' >Coquimbo<\/option><option value='Illapel' >Illapel<\/option><option value='La Higuera' >La Higuera<\/option><option value='La Serena' >La Serena<\/option><option value='Los Vilos' >Los Vilos<\/option><option value='Ovalle' >Ovalle<\/option><option value='Paiguano' >Paiguano<\/option><option value='Punitaqui' >Punitaqui<\/option><option value='R\u00edo Hurtado' >R\u00edo Hurtado<\/option><option value='Salamanca' >Salamanca<\/option><option value='Vicu\u00f1a' >Vicu\u00f1a<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_19' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_19' >Comunas Maule:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_19' id='input_11_19'  class='medium gfield_select' tabindex='15'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Cauquenes' >Cauquenes<\/option><option value='Chanco' >Chanco<\/option><option value='Colb\u00fan' >Colb\u00fan<\/option><option value='Constituci\u00f3n' >Constituci\u00f3n<\/option><option value='Curepto' >Curepto<\/option><option value='Curic\u00f3' >Curic\u00f3<\/option><option value='Empedrado' >Empedrado<\/option><option value='Huala\u00f1e' >Huala\u00f1e<\/option><option value='Licant\u00e9n' >Licant\u00e9n<\/option><option value='Linares' >Linares<\/option><option value='Longav\u00ed' >Longav\u00ed<\/option><option value='Maule' >Maule<\/option><option value='Molina' >Molina<\/option><option value='Parral' >Parral<\/option><option value='Pelarco' >Pelarco<\/option><option value='Pelluhue' >Pelluhue<\/option><option value='Pencahue' >Pencahue<\/option><option value='Rauco' >Rauco<\/option><option value='Retiro' >Retiro<\/option><option value='R\u00edo Claro' >R\u00edo Claro<\/option><option value='Romeral' >Romeral<\/option><option value='Sagrada Familia' >Sagrada Familia<\/option><option value='San Clemente' >San Clemente<\/option><option value='San Javier' >San Javier<\/option><option value='San Rafael' >San Rafael<\/option><option value='Talca' >Talca<\/option><option value='Teno' >Teno<\/option><option value='Vichuqu\u00e9n' >Vichuqu\u00e9n<\/option><option value='Villa Alegre' >Villa Alegre<\/option><option value='Yerbas Buenas' >Yerbas Buenas<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_20' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_20' >Comunas Biobio:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_20' id='input_11_20'  class='medium gfield_select' tabindex='16'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Antuco' >Antuco<\/option><option value='Arauco' >Arauco<\/option><option value='Bulnes' >Bulnes<\/option><option value='Cabrero' >Cabrero<\/option><option value='Ca\u00f1ete' >Ca\u00f1ete<\/option><option value='Chiguayante' >Chiguayante<\/option><option value='Chill\u00e1n' >Chill\u00e1n<\/option><option value='Chill\u00e1n Viejo' >Chill\u00e1n Viejo<\/option><option value='Cobquecura' >Cobquecura<\/option><option value='Coelemu' >Coelemu<\/option><option value='Coihueco' >Coihueco<\/option><option value='Concepci\u00f3n' >Concepci\u00f3n<\/option><option value='Contulmo' >Contulmo<\/option><option value='Coronel' >Coronel<\/option><option value='Curanilahue' >Curanilahue<\/option><option value='El Carmen' >El Carmen<\/option><option value='Florida' >Florida<\/option><option value='Hualqui' >Hualqui<\/option><option value='Laja' >Laja<\/option><option value='Lebu' >Lebu<\/option><option value='Los \u00e1lamos' >Los \u00e1lamos<\/option><option value='Los \u00e1ngeles' >Los \u00e1ngeles<\/option><option value='Lota' >Lota<\/option><option value='Mulch\u00e9n' >Mulch\u00e9n<\/option><option value='Nacimiento' >Nacimiento<\/option><option value='Negrete' >Negrete<\/option><option value='Ninhue' >Ninhue<\/option><option value='\u00d1iqu\u00e9n' >\u00d1iqu\u00e9n<\/option><option value='Pemuco' >Pemuco<\/option><option value='Penco' >Penco<\/option><option value='Pinto' >Pinto<\/option><option value='Portezuelo' >Portezuelo<\/option><option value='Quilaco' >Quilaco<\/option><option value='Quilleco' >Quilleco<\/option><option value='Quill\u00f3n' >Quill\u00f3n<\/option><option value='Quirihue' >Quirihue<\/option><option value='Ranquil' >Ranquil<\/option><option value='San Carlos' >San Carlos<\/option><option value='San Fabi\u00e1n' >San Fabi\u00e1n<\/option><option value='San Ignacio' >San Ignacio<\/option><option value='San Nicol\u00e1s' >San Nicol\u00e1s<\/option><option value='San Pedro de la Paz' >San Pedro de la Paz<\/option><option value='San Rosendo' >San Rosendo<\/option><option value='Santa B\u00e1rbara' >Santa B\u00e1rbara<\/option><option value='Santa Juana' >Santa Juana<\/option><option value='Talcahuano' >Talcahuano<\/option><option value='Tir\u00faa' >Tir\u00faa<\/option><option value='Tom\u00e9' >Tom\u00e9<\/option><option value='Treguaco' >Treguaco<\/option><option value='Tucapel' >Tucapel<\/option><option value='Yumbel' >Yumbel<\/option><option value='Yungay' >Yungay<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_21' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_21' >Comunas Los Rios:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_21' id='input_11_21'  class='medium gfield_select' tabindex='17'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Corral' >Corral<\/option><option value='Futrono' >Futrono<\/option><option value='La Uni\u00f3n' >La Uni\u00f3n<\/option><option value='Lago Ranco' >Lago Ranco<\/option><option value='Lanco' >Lanco<\/option><option value='Los Lagos' >Los Lagos<\/option><option value='M\u00e1fil' >M\u00e1fil<\/option><option value='Mariquina' >Mariquina<\/option><option value='Paillaco' >Paillaco<\/option><option value='Panguipulli' >Panguipulli<\/option><option value='R\u00edo Bueno' >R\u00edo Bueno<\/option><option value='Valdivia' >Valdivia<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_22' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_22' >Comunas Los Lagos:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_22' id='input_11_22'  class='medium gfield_select' tabindex='18'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Ancud' >Ancud<\/option><option value='Calbuco' >Calbuco<\/option><option value='Castro' >Castro<\/option><option value='Chait\u00e9n' >Chait\u00e9n<\/option><option value='Chonchi' >Chonchi<\/option><option value='Cocham\u00f3' >Cocham\u00f3<\/option><option value='Curaco de V\u00e9lez' >Curaco de V\u00e9lez<\/option><option value='Dalcahue' >Dalcahue<\/option><option value='Fresia' >Fresia<\/option><option value='Frutillar' >Frutillar<\/option><option value='Futaleuf\u00fa' >Futaleuf\u00fa<\/option><option value='Hualaihu\u00e9' >Hualaihu\u00e9<\/option><option value='Llanquihue' >Llanquihue<\/option><option value='Los Muermos' >Los Muermos<\/option><option value='Maull\u00edn' >Maull\u00edn<\/option><option value='Osorno' >Osorno<\/option><option value='Palena' >Palena<\/option><option value='Puerto Montt' >Puerto Montt<\/option><option value='Puerto Octay' >Puerto Octay<\/option><option value='Puerto Varas' >Puerto Varas<\/option><option value='Puqueld\u00f3n' >Puqueld\u00f3n<\/option><option value='Purranque' >Purranque<\/option><option value='Puyehue' >Puyehue<\/option><option value='Queil\u00e9n' >Queil\u00e9n<\/option><option value='Quell\u00f3n' >Quell\u00f3n<\/option><option value='Quemchi' >Quemchi<\/option><option value='Quinchao' >Quinchao<\/option><option value='R\u00edo Negro' >R\u00edo Negro<\/option><option value='San Juan de la Costa' >San Juan de la Costa<\/option><option value='San Pablo' >San Pablo<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_23' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_23' >Comunas Aysen:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_23' id='input_11_23'  class='medium gfield_select' tabindex='19'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Ays\u00e9n' >Ays\u00e9n<\/option><option value='Chile Chico' >Chile Chico<\/option><option value='Cisnes' >Cisnes<\/option><option value='Cochrane' >Cochrane<\/option><option value='Coihaique' >Coihaique<\/option><option value='Guaitecas' >Guaitecas<\/option><option value='Lago Verde' >Lago Verde<\/option><option value='O`Higgins' >O`Higgins<\/option><option value='R\u00edo Iba\u00f1ez' >R\u00edo Iba\u00f1ez<\/option><option value='Tortel' >Tortel<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_24' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_24' >Comunas Magallanes:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_24' id='input_11_24'  class='medium gfield_select' tabindex='20'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Ant\u00e1rtica' >Ant\u00e1rtica<\/option><option value='Cabo de Hornos' >Cabo de Hornos<\/option><option value='Laguna Blanca' >Laguna Blanca<\/option><option value='Natales' >Natales<\/option><option value='Porvenir' >Porvenir<\/option><option value='Primavera' >Primavera<\/option><option value='Punta Arenas' >Punta Arenas<\/option><option value='R\u00edo Verde' >R\u00edo Verde<\/option><option value='San Gregorio' >San Gregorio<\/option><option value='Timaukel' >Timaukel<\/option><option value='Torres del Paine' >Torres del Paine<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_25' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_25' >Comunas OHiggins:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_25' id='input_11_25'  class='medium gfield_select' tabindex='21'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Ch\u00e9pica' >Ch\u00e9pica<\/option><option value='Chimbar\u00f3ngo' >Chimbar\u00f3ngo<\/option><option value='Codegua' >Codegua<\/option><option value='Coinco' >Coinco<\/option><option value='Coltauco' >Coltauco<\/option><option value='Do\u00f1ihue' >Do\u00f1ihue<\/option><option value='Graneros' >Graneros<\/option><option value='La Estrella' >La Estrella<\/option><option value='Las Cabras' >Las Cabras<\/option><option value='Litueche' >Litueche<\/option><option value='Lolol' >Lolol<\/option><option value='Machal\u00ed' >Machal\u00ed<\/option><option value='Malloa' >Malloa<\/option><option value='Marchihue' >Marchihue<\/option><option value='Mostazal' >Mostazal<\/option><option value='Nancahua' >Nancahua<\/option><option value='Navidad' >Navidad<\/option><option value='Olivar' >Olivar<\/option><option value='Palmilla' >Palmilla<\/option><option value='Paredones' >Paredones<\/option><option value='Peralillo' >Peralillo<\/option><option value='Peumo' >Peumo<\/option><option value='Pichidehua' >Pichidehua<\/option><option value='Pichilemu' >Pichilemu<\/option><option value='Placilla' >Placilla<\/option><option value='Pumanque' >Pumanque<\/option><option value='Quinta de Tilcoco' >Quinta de Tilcoco<\/option><option value='Rancagua' >Rancagua<\/option><option value='Rengo' >Rengo<\/option><option value='Requ\u00ednoa' >Requ\u00ednoa<\/option><option value='San Fernando' >San Fernando<\/option><option value='San Vicente' >San Vicente<\/option><option value='Santa Cruz' >Santa Cruz<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_26' class='gfield gf_right_half gfield_contains_required field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_26' >Comunas Araucania:<span class='gfield_required'>*<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_26' id='input_11_26'  class='medium gfield_select' tabindex='22'  aria-required=\"true\" aria-invalid=\"false\"><option value='' >Seleccionar<\/option><option value='Angol' >Angol<\/option><option value='Carahue' >Carahue<\/option><option value='Collipulli' >Collipulli<\/option><option value='Cunco' >Cunco<\/option><option value='Curacaut\u00edn' >Curacaut\u00edn<\/option><option value='Curarrehue' >Curarrehue<\/option><option value='Ercilla' >Ercilla<\/option><option value='Freire' >Freire<\/option><option value='Galvarino' >Galvarino<\/option><option value='Gorbea' >Gorbea<\/option><option value='Lautaro' >Lautaro<\/option><option value='Loncoche' >Loncoche<\/option><option value='Lonquimay' >Lonquimay<\/option><option value='Los Sauces' >Los Sauces<\/option><option value='Lumaco' >Lumaco<\/option><option value='Melipeuco' >Melipeuco<\/option><option value='Nueva Imperial' >Nueva Imperial<\/option><option value='Padre las Casas' >Padre las Casas<\/option><option value='Perquenco' >Perquenco<\/option><option value='Pitrufqu\u00e9n' >Pitrufqu\u00e9n<\/option><option value='Puc\u00f3n' >Puc\u00f3n<\/option><option value='Pur\u00e9n' >Pur\u00e9n<\/option><option value='Renaico' >Renaico<\/option><option value='Saavedra' >Saavedra<\/option><option value='Temuco' >Temuco<\/option><option value='Teodoro Schmidt' >Teodoro Schmidt<\/option><option value='Tolt\u00e9n' >Tolt\u00e9n<\/option><option value='Traigu\u00e9n' >Traigu\u00e9n<\/option><option value='Victoria' >Victoria<\/option><option value='Vilc\u00fan' >Vilc\u00fan<\/option><option value='Villarrica' >Villarrica<\/option><option value='Comuna sin definir' >Otra<\/option><\/select><\/div><\/li><li id='field_11_5' class='gfield field_sublabel_above field_description_below gfield_visibility_visible' ><label class='gfield_label' for='input_11_5' >Mensaje:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_5' id='input_11_5' class='textarea small' tabindex='23'    aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id='field_11_28' class='gfield gform_validation_container field_sublabel_above field_description_below gfield_visibility_' ><label class='gfield_label' for='input_11_28' >Phone<\/label><div class='ginput_container'><input name='input_28' id='input_11_28' type='text' value='' \/><\/div><div class='gfield_description'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/li>\n                            <\/ul><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_11' class='gform_button button' value='Enviar solicitud' tabindex='24' onclick='if(window[\"gf_submitting_11\"]){return false;}  window[\"gf_submitting_11\"]=true;  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_11\"]){return false;} window[\"gf_submitting_11\"]=true;  jQuery(\"#gform_11\").trigger(\"submit\",[true]); }' \/> \n            <input type='hidden' class='gform_hidden' name='is_submit_11' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='11' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_11' value='WyJbXSIsImQzNzM4YzAyOWZkOTc4MDg5MmQzMDc1ODg1ZTA3ODc2Il0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_11' id='gform_target_page_number_11' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_11' id='gform_source_page_number_11' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"51\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><\/form>\n                        <\/div><script type='text\/javascript'> if(typeof gf_global == 'undefined') var gf_global = {\"gf_currency_config\":{\"name\":\"Peso Mexicano\",\"symbol_left\":\"$\",\"symbol_right\":\"\",\"symbol_padding\":\" \",\"thousand_separator\":\",\",\"decimal_separator\":\".\",\"decimals\":2},\"base_url\":\"https:\\\/\\\/catalogo.autosonline.cl\\\/autos-nuevos\\\/wp-content\\\/plugins\\\/gravityforms\",\"number_formats\":[],\"spinnerUrl\":\"https:\\\/\\\/catalogo.autosonline.cl\\\/autos-nuevos\\\/wp-content\\\/plugins\\\/gravityforms\\\/images\\\/spinner.gif\"};jQuery(document).bind('gform_post_render', function(event, formId, currentPage){if(formId == 11) {gf_global[\"number_formats\"][11] = {\"10\":{\"price\":false,\"value\":false},\"8\":{\"price\":false,\"value\":false},\"1\":{\"price\":false,\"value\":false},\"9\":{\"price\":false,\"value\":false},\"27\":{\"price\":false,\"value\":false},\"3\":{\"price\":false,\"value\":false},\"4\":{\"price\":false,\"value\":false},\"11\":{\"price\":false,\"value\":false},\"12\":{\"price\":false,\"value\":false},\"13\":{\"price\":false,\"value\":false},\"14\":{\"price\":false,\"value\":false},\"15\":{\"price\":false,\"value\":false},\"16\":{\"price\":false,\"value\":false},\"17\":{\"price\":false,\"value\":false},\"18\":{\"price\":false,\"value\":false},\"19\":{\"price\":false,\"value\":false},\"20\":{\"price\":false,\"value\":false},\"21\":{\"price\":false,\"value\":false},\"22\":{\"price\":false,\"value\":false},\"23\":{\"price\":false,\"value\":false},\"24\":{\"price\":false,\"value\":false},\"25\":{\"price\":false,\"value\":false},\"26\":{\"price\":false,\"value\":false},\"5\":{\"price\":false,\"value\":false},\"28\":{\"price\":false,\"value\":false}};if(window['jQuery']){if(!window['gf_form_conditional_logic'])window['gf_form_conditional_logic'] = new Array();window['gf_form_conditional_logic'][11] = { logic: { 12: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"RM - Metropolitana de Santiago\"}]},\"nextButton\":null,\"section\":null},13: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"V - Valpara\\u00edso\"}]},\"nextButton\":null,\"section\":null},14: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"XV - Arica y Parinacota\"}]},\"nextButton\":null,\"section\":null},15: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"I - Tarapac\\u00e1\"}]},\"nextButton\":null,\"section\":null},16: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"II - Antofagasta\"}]},\"nextButton\":null,\"section\":null},17: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"III - Atacama\"}]},\"nextButton\":null,\"section\":null},18: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"IV - Coquimbo\"}]},\"nextButton\":null,\"section\":null},19: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"VII - Maule\"}]},\"nextButton\":null,\"section\":null},20: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"VIII - Biob\\u00edo\"}]},\"nextButton\":null,\"section\":null},21: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"XIV - Los R\\u00edos\"}]},\"nextButton\":null,\"section\":null},22: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"X - Los Lagos\"}]},\"nextButton\":null,\"section\":null},23: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"XI - Ays\\u00e9n\"}]},\"nextButton\":null,\"section\":null},24: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"XII - Magallanes\"}]},\"nextButton\":null,\"section\":null},25: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"VI - O'Higgins\"}]},\"nextButton\":null,\"section\":null},26: {\"field\":{\"actionType\":\"show\",\"logicType\":\"all\",\"rules\":[{\"fieldId\":\"11\",\"operator\":\"is\",\"value\":\"IX - Araucan\\u00eda\"}]},\"nextButton\":null,\"section\":null} }, dependents: { 12: [12],13: [13],14: [14],15: [15],16: [16],17: [17],18: [18],19: [19],20: [20],21: [21],22: [22],23: [23],24: [24],25: [25],26: [26] }, animation: 0, defaults: {\"10\":[\"choice_11_10_0\"],\"8\":\"\",\"11\":\"\",\"12\":\"\",\"13\":\"\",\"14\":\"\",\"15\":\"\",\"16\":\"\",\"17\":\"\",\"18\":\"\",\"19\":\"\",\"20\":\"\",\"21\":\"\",\"22\":\"\",\"23\":\"\",\"24\":\"\",\"25\":\"\",\"26\":\"\"}, fields: {\"10\":[],\"8\":[],\"1\":[],\"9\":[],\"27\":[],\"3\":[],\"4\":[],\"11\":[12,13,14,15,16,17,18,19,20,21,22,23,24,25,26],\"12\":[],\"13\":[],\"14\":[],\"15\":[],\"16\":[],\"17\":[],\"18\":[],\"19\":[],\"20\":[],\"21\":[],\"22\":[],\"23\":[],\"24\":[],\"25\":[],\"26\":[],\"5\":[],\"28\":[]} }; if(!window['gf_number_format'])window['gf_number_format'] = 'decimal_comma';jQuery(document).ready(function(){gf_apply_rules(11, [12,13,14,15,16,17,18,19,20,21,22,23,24,25,26], true);jQuery('#gform_wrapper_11').show();jQuery(document).trigger('gform_post_conditional_logic', [11, null, true]);} );} } } );jQuery(document).bind('gform_post_conditional_logic', function(event, formId, fields, isInit){} );<\/script><script type='text\/javascript'> jQuery(document).ready(function(){jQuery(document).trigger('gform_post_render', [11, 1]) } ); <\/script>\n<\/div><\/section><\/p><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='after_section_1' class='main_color av_default_container_wrap container_wrap sidebar_right'   ><div class='container' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-12847'><div class='entry-content-wrapper clearfix'>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><p><div style='padding-bottom:10px;color:#83a846;font-size:40px;' class='av-special-heading av-special-heading-h2 custom-color-heading blockquote modern-quote  av-inherit-size '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Mazda BT 50, precio, informaci\u00f3n e im\u00e1genes<\/h2><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#83a846'><\/div><\/div><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '  style='font-size:16px; '  itemprop=\"text\" ><p>Mazda BT-50 es una incre\u00edble propuesta de esta marca. Que posee el exterior de una atl\u00e9tica e imponente pick up y el interior de un c\u00f3modo SUV. Su exterior es atrevido, juvenil e innovador. Un auto elaborado para resistir cualquier misi\u00f3n y siempre con gran estilo.<br \/>\nSe trata de un veh\u00edculo que fue especialmente dise\u00f1ado para la realizaci\u00f3n de todos los tipos de terrenos y actividades al aire libre. Adem\u00e1s de labores de trabajo pesado. Y esto porque posee una capacidad para carga por sobre 1 tonelada.<br \/>\nA lo anterior, se suma su full equipamiento enfocado en seguridad y confort.<br \/>\nEn cuanto a su motorizaci\u00f3n, se puede mencionar que posee 2,5 litros de capacidad. De tecnolog\u00eda manual y con 5 velocidades. Para la versi\u00f3n 4&#215;4, existe conducci\u00f3n autom\u00e1tica. El tipo de combustible que ocupa es Diesel y cumple con la exigente normativa de emisiones de la Euro V. Posee excelente rendimiento urbano, mixto y extraurbano.<br \/>\nEn Autosnuevoschile, encuentra el mejor precio de esta impresionante pick up. Que se convertir\u00e1 en tu mejor vers\u00e1til aliado para tus actividades recreativas como de trabajo.<br \/>\nSolicita el tuyo con los m\u00e1s reconocidos concesionarios del pa\u00eds.<\/p>\n<\/div><\/section><\/p><\/div><div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><p><div style='padding-bottom:10px;color:#83a846;font-size:40px;' class='av-special-heading av-special-heading-h2 custom-color-heading blockquote modern-quote  av-inherit-size '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Galer\u00eda Mazda BT 50<\/h2><div class ='av-subheading av-subheading_below av_custom_color ' style='font-size:15px;'><p>Descubre im\u00e1genes Mazda BT 50<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#83a846'><\/div><\/div><\/div><br \/>\n<br \/>\n<div class='av-woo-product-info '><\/div><br \/>\n<div class=\"togglecontainer  av-mini-hide toggle_close_all \">\n<section class=\"av_toggle_section\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" >    <div class=\"single_toggle\" data-tags=\"{Todo} \" >        <p data-fake-id=\"#toggle-id-1\" class=\"toggler \"  itemprop=\"headline\" >Saber m\u00e1s<span class=\"toggle_icon\">        <span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p>        <div id=\"toggle-id-1-container\" class=\"toggle_wrap \" >            <div class=\"toggle_content invers-color\"  itemprop=\"text\" ><h4>Seguridad Mazda BT-50<\/h4>\n<p>La pick up Mazda B-50 posee una excelente performance en seguridad. Para comenzar se pueden mencionar su innovador sistema inmovilizador del motor para frustrar robos.<br \/>\nSe suman sus sistemas de frenos ABS en sus 4 ruedas m\u00e1s la tecnolog\u00eda EBD.<br \/>\nTambi\u00e9n cuenta con airbags frontales, para pasajero y conductor. Se suma la cl\u00e1sica alarma antirrobo pero con sensor volum\u00e9trico.<br \/>\nFinalmente cinturones traseros, delanteros y traseros central con 3 puntas. Solamente en delantero posee pretensionador.<\/p>\n<h4>Exterior BT-50 de\u00a0Mazda<\/h4>\n<p>La pick up Mazda B-50 presenta una carrocer\u00eda imponente, robusta y atl\u00e9tica. Su dise\u00f1o, evoca la imagen de un gran caballo de batalla siempre preparado para el desaf\u00edo.<br \/>\nEl estilo de esta camioneta es de alta gama, potencia y grandeza. Que la convierten en un veh\u00edculo muy atractivo.<br \/>\nEn referencia a su pick up, posee una poderosa capacidad de 950 kilos. Compuesto por doble pared de metal y una multifac\u00e9tica funci\u00f3n. Se trata de separador de carga y doble fondo.<br \/>\nEl chasis de este modelo es doble y de propuesta escalera y faros en la zona delantera de policarbonato. De esto \u00faltimo un mecanismo multi reflector adem\u00e1s de limpiaparabrisas semicultos.<\/p>\n<h4>Interior BT-50 de\u00a0Mazda<\/h4>\n<p>La pick up Mazda B-50, posee un habit\u00e1culo interior, imponente, confortable y tecnol\u00f3gico. Dentro de su equipamiento se destaca su tablero de \u00f3ptima visibilidad, de hermoso color \u00e1mbar. El que a su vez se puede regular en intensidad o altura de las luces exteriores desde el mismo interior.<br \/>\nEn cuanto a conectividad posee radio digital est\u00e9reo, que reproduce MP3, disco, Bluetooth y audio streaming. Esto acompa\u00f1ado de un sistema de audio compuesto por 6 parlantes y 2 ubicados en las puertas delanteras.<br \/>\nEn referencia a confort, posee volante de lujo, es regulable en su altura. Se suman los c\u00f3modos apoyabrazos ubicados en las 4 puertas y el piso est\u00e1 elegantemente tapizado.<\/p>\n            <\/div>        <\/div>    <\/div><\/section>\n<\/div><\/p><\/div><div class='avia-builder-widget-area clearfix '><div id=\"custom_html-4\" class=\"widget_text widget clearfix widget_custom_html\"><div class=\"textwidget custom-html-widget\"><br>\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/autos-nuevos.html' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Autos Nuevos<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/autos-chinos.html' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Autos Chinos<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/categorias.html' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Tipos de autos<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/credito-automotriz\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Credito automotriz<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/neumaticos\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Neum\u00e1ticos<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/accesorios\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Accesorios<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/servicios\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Servicios<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/servicio-tecnico\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Servicio t\u00e9cnico<\/span><\/a><\/div>\r\n\r\n<div class='avia-button-wrap avia-button-right '><a href='https:\/\/www.autosonline.cl\/repuestos-para-vehiculos\/' class='avia-button   avia-icon_select-no avia-color-light avia-size-medium avia-position-right '  target=\"_blank\"   ><span class='avia_iconbox_title' >Repuestos<\/span><\/a><\/div>\r\n<\/div><\/div><\/div><\/p>\n<div class='flex_column_table av-equal-height-column-flextable -flextable' ><div class=\"flex_column av_one_half  av-hide-on-mobile  no_margin flex_column_table_cell av-equal-height-column av-align-top first  \" style='padding:30px; background-color:#3f5d75; border-radius:0px; '><p><div style='height:60px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<div style='padding-bottom:0px;color:#ffffff;font-size:30px;' class='av-special-heading av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >\u00bfNecesitas<br \/>\nCredito Automotriz?<\/h3><div class ='av-subheading av-subheading_below av_custom_color ' style='font-size:17px;'><p>Informate sobre ventajas, tipos de credito automotriz y recomendaciones<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#ffffff'><\/div><\/div><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-equal-height-column-flextable -flextable' ><div class=\"flex_column av_one_half  av-hide-on-mobile  no_margin flex_column_table_cell av-equal-height-column av-align-top   \" style='padding:30px; background-color:#0099ff; border-radius:0px; '><p><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  av_inherit_color '  style='font-size:15px; color:#ffffff; '  itemprop=\"text\" ><p><strong>Si necesitas comprar hoy\u00a0tu auto nuevo<\/strong> te invitamos a descubrir todo sobre\u00a0<a title=\"Credito Automotriz\" href=\"https:\/\/www.autosnuevoschile.cl\/credito-automotriz\/\">credito automotriz<\/a>, la mejor alternativa para adquirir el modelo 0km que tanto buscas al instante. Encuentra\u00a0informaci\u00f3n, recomendaciones con los\u00a0<a title=\"Tipos de Credito Automotriz\" href=\"https:\/\/www.autosnuevoschile.cl\/credito-automotriz\/#tipos\">tipos de credito automotriz<\/a>\u00a0para escoger la mejor opci\u00f3n\u00a0y as\u00ed obtener tu auto so\u00f1ado.<\/p>\n<\/div><\/section><br \/>\n<div class='avia-button-wrap avia-button-left '><a href='https:\/\/catalogo.autosonline.cl\/autos-nuevos\/mazda\/bt-50\/' class='avia-button   avia-icon_select-yes-left-icon avia-color-light avia-size-large avia-position-left '   ><span class='avia_button_icon avia_button_icon_left ' aria-hidden='true' data-av_icon='\ue816' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Saber m\u00e1s<\/span><\/a><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mazda BT-50 es una incre\u00edble propuesta de esta marca. Que posee el exterior de una atl\u00e9tica e imponente pick up y el interior de un c\u00f3modo SUV. Su exterior es atrevido, juvenil e innovador A.<\/p>\n","protected":false},"featured_media":21919,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[207,205],"product_tag":[212,213],"class_list":{"0":"post-12847","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mazda","7":"product_cat-ofertas","8":"product_tag-camionetas","9":"product_tag-pick-up","11":"first","12":"instock","13":"sale","14":"virtual","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/product\/12847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/comments?post=12847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/media\/21919"}],"wp:attachment":[{"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/media?parent=12847"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/product_brand?post=12847"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/product_cat?post=12847"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/catalogo.autosonline.cl\/autos-nuevos\/wp-json\/wp\/v2\/product_tag?post=12847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}